{"id":2183,"date":"2024-03-15T10:08:07","date_gmt":"2024-03-15T10:08:07","guid":{"rendered":"https:\/\/www.escolaginestaripollet.cat\/arquitectos\/nuestro-estudio-2\/"},"modified":"2026-02-05T14:14:23","modified_gmt":"2026-02-05T14:14:23","slug":"contacte","status":"publish","type":"page","link":"https:\/\/www.escolaginestaripollet.cat\/es\/contacte\/","title":{"rendered":"CONTACTE"},"content":{"rendered":"<div id=\"fws_6a04610254ca0\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1229\" width=\"2560\" data-animation=\"none\" src=\"https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-scaled.jpg\" alt=\"\" srcset=\"https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-scaled.jpg 2560w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-300x144.jpg 300w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-1024x492.jpg 1024w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-768x369.jpg 768w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-1536x738.jpg 1536w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-2048x983.jpg 2048w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/IMG_4677-1-18x9.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04610255573\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a04610255816\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding left_margin_120px top_margin_tablet_0px top_margin_phone_0px right_margin_phone_15px left_margin_tablet_18px left_margin_phone_17px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1770195753249\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<div class=\"xat24cr\">\n<div class=\"x13faqbe x78zum5 xdt5ytf\">\n<div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 x1r8uery x1iyjqo2 xs83m0k xeuugli x1nhvcw1 x1qjc9v5 xozqiw3 x1q0g3np xexx8yu xykv574 xbmpl8g x4cne27 xifccgj\">\n<div class=\"x9f619 x1n2onr6 x1ja2u2z x78zum5 xdt5ytf x2lah0s x193iq5w xeuugli xsyo7zv x16hj40l x10b6aqq x1yrsyyn\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 100px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<div class=\"brando_inner_row_1622739106-2-9 brando-inner-row-class\">\n<div class=\"wpb_column brando-column-container vc_col-sm-12 col-xs-mobile-fullwidth\">\n<div class=\"vc-column-innner-wrapper\">\n<div class=\"wpd-innner-wrapper\">\n<div class=\"brando-remove-frontend-editor-top\">\n<div class=\"col-md-10 col-sm-10\">\n<h3><span class=\"text-uppercase alt-font black-text text-large font-weight-700\" style=\"color: #808080;\">ESCOLA GINESTA RIPOLLET<\/span><\/h3>\n<p class=\"text-medium\"><span style=\"color: #808080;\">Carrer Puigmal,59<\/span><br \/>\n<span style=\"color: #808080;\">08291-Ripollet<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brando_inner_row_1622739115-2-13 brando-inner-row-class\">\n<div class=\"wpb_column brando-column-container vc_col-sm-12 col-xs-mobile-fullwidth\">\n<div class=\"vc-column-innner-wrapper\">\n<div class=\"wpd-innner-wrapper\">\n<div class=\"brando-remove-frontend-editor-top\">\n<div class=\"col-md-2 col-sm-1\"><\/div>\n<div class=\"col-md-10 col-sm-10\">\n<h4><span style=\"color: #808080;\"><em><span class=\"text-uppercase alt-font black-text text-large font-weight-700\">Truqui\u00b4 ns<\/span><\/em><\/span><\/h4>\n<p class=\"text-medium\"><span style=\"color: #808080;\">Tel\u00e8fon: <a href=\"tel:936922791\"><strong><span style=\"color: #808080;\">93 692 27 91<\/span><\/strong><\/a><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"brando_inner_row_1622739142-2-27 brando-inner-row-class\">\n<div class=\"wpb_column brando-column-container vc_col-sm-12 col-xs-mobile-fullwidth\">\n<div class=\"vc-column-innner-wrapper\">\n<div class=\"wpd-innner-wrapper\">\n<div class=\"brando-remove-frontend-editor-top\">\n<div class=\"col-md-2 col-sm-1\"><\/div>\n<div class=\"col-md-10 col-sm-10\">\n<p><span class=\"text-uppercase alt-font black-text text-large font-weight-700\" style=\"color: #808080;\">Correu: <\/span><a href=\"mailto:a8023554@xtec.cat\"><span style=\"color: #333333;\"><span style=\"color: #808080;\">a8023554@xtec.cat<\/span><\/span><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 50px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"161\" width=\"300\" data-animation=\"none\" src=\"https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/GOO-300x161.png\" alt=\"\" srcset=\"https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/GOO-300x161.png 300w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/GOO-1024x550.png 1024w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/GOO-768x413.png 768w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/GOO-1536x826.png 1536w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/GOO-18x10.png 18w, https:\/\/www.escolaginestaripollet.cat\/wp-content\/uploads\/2026\/02\/GOO.png 1682w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 120px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<div id=\"wpgmza_map\" class=\"wpgmza_map\" data-settings='{\"id\":\"1\",\"map_title\":\"ESCOLA GINESTA\",\"map_width\":\"100\",\"map_height\":\"400\",\"map_start_lat\":\"41.50552874521952\",\"map_start_lng\":\"2.15468206322937\",\"map_start_location\":\"45.950464398418106,-109.81550500000003\",\"map_start_zoom\":\"16\",\"default_marker\":\"\",\"type\":\"0\",\"alignment\":\"4\",\"directions_enabled\":\"0\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"0\",\"dbox_width\":\"\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"0\",\"ugm_access\":\"0\",\"order_markers_by\":\"0\",\"order_markers_choice\":\"0\",\"show_user_location\":\"0\",\"default_to\":\"\",\"other_settings\":{\"map_type\":1,\"sl_stroke_color\":\"\",\"sl_fill_color\":\"\",\"sl_stroke_opacity\":\"\",\"sl_fill_opacity\":\"\",\"transport_layer\":false,\"action\":\"wpgmza_save_map\",\"redirect_to\":\"\\\/wp-admin\\\/admin-post.php\",\"map_id\":\"1\",\"http_referer\":\"\\\/av\\\/wp-admin\\\/admin.php?page=wp-google-maps-menu&amp;amp;action=edit&amp;amp;map_id=1\",\"wpgmza_id\":\"1\",\"wpgmza_start_location\":\"41.50552874521952,2.15468206322937\",\"wpgmza_start_zoom\":\"18\",\"store_locator_enabled\":false,\"store_locator_search_area\":\"radial\",\"wpgmza_store_locator_radius_style\":\"legacy\",\"wpgmza_store_locator_default_radius\":\"10\",\"store_locator_auto_area_max_zoom\":\"\",\"store_locator_distance\":false,\"wpgmza_store_locator_position\":false,\"store_locator_show_distance\":false,\"store_locator_category\":false,\"wpgmza_store_locator_use_their_location\":false,\"wpgmza_store_locator_bounce\":false,\"wpgmza_sl_animation\":null,\"wpgmza_store_locator_hide_before_search\":false,\"store_locator_query_string\":\"\",\"store_locator_location_placeholder\":\"\",\"store_locator_default_address\":\"\",\"store_locator_name_search\":false,\"store_locator_name_string\":\"\",\"store_locator_not_found_message\":\"\",\"wpgmza_map_align\":\"1\",\"jump_to_nearest_marker_on_initialization\":false,\"automatically_pan_to_users_location\":false,\"override_users_location_zoom_level\":false,\"override_users_location_zoom_levels\":\"\",\"show_distance_from_location\":false,\"map_max_zoom\":\"21\",\"map_min_zoom\":\"0\",\"click_open_link\":false,\"fit_maps_bounds_to_markers\":false,\"fit_maps_bounds_to_markers_after_filtering\":false,\"hide_point_of_interest\":false,\"wpgmza_zoom_on_marker_click\":false,\"wpgmza_zoom_on_marker_click_slider\":\"\",\"close_infowindow_on_map_click\":false,\"disable_lightbox_images\":false,\"use_Raw_Jpeg_Coordinates\":false,\"disable_polygon_info_windows\":false,\"enable_marker_ratings\":false,\"only_load_markers_within_viewport\":false,\"zoom_level_mobile_override_enabled\":false,\"zoom_level_mobile_override\":\"\",\"iw_primary_color\":\"#000000\",\"iw_accent_color\":\"#000000\",\"iw_text_color\":\"#000000\",\"wpgmza_listmarkers_by\":\"0\",\"wpgmza_marker_listing_position\":false,\"zoom_level_on_marker_listing_override\":false,\"zoom_level_on_marker_listing_click\":\"\",\"marker_listing_disable_zoom\":false,\"datatable_no_result_message\":\"\",\"remove_search_box_datables\":false,\"dataTable_pagination_style\":null,\"datatable_search_string\":\"\",\"datatable_result_start\":\"\",\"datatable_result_of\":\"\",\"datatable_result_to\":\"\",\"datatable_result_total\":\"\",\"datatable_result_show\":\"\",\"datatable_result_entries\":\"\",\"wpgmza_savemap\":\"Guardar Mapa \\u00bb\",\"enable_marker_labels\":false}}' data-map-id='1' data-maps-engine='open-layers' data-shortcode-attributes='{\"id\":\"1\"}' style=\"display:block; overflow:auto; width:100%; height:400px; float:left;\"><\/div>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 100px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"ESCOLA GINESTA RIPOLLET Carrer Puigmal,59 08291-Ripollet Truqui\u00b4 ns Tel\u00e8fon: 93 692 27 91 Correu: a8023554@xtec.cat","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2183","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/pages\/2183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/comments?post=2183"}],"version-history":[{"count":84,"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/pages\/2183\/revisions"}],"predecessor-version":[{"id":3593,"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/pages\/2183\/revisions\/3593"}],"wp:attachment":[{"href":"https:\/\/www.escolaginestaripollet.cat\/es\/wp-json\/wp\/v2\/media?parent=2183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}